{"id":5960,"date":"2017-11-14T19:46:11","date_gmt":"2017-11-14T19:46:11","guid":{"rendered":"http:\/\/centresmolina.com\/centreensenyament\/2017\/11\/14\/sra-leonor-garuz-blanco\/"},"modified":"2017-11-14T19:52:25","modified_gmt":"2017-11-14T19:52:25","slug":"sra-leonor-garuz-blanco","status":"publish","type":"post","link":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/","title":{"rendered":"Sra. Leonor Garuz Blanco"},"content":{"rendered":"<p>Os informamos del fallecimiento de la estimada Sra Leonor Garuz Blanco, fundadora de Colegio Molina.<\/p>\n<p>El velatorio tendr\u00e1 lugar en el Tanatorio de Sancho de \u00c1vila, Capilla 18, a partir de ma\u00f1ana mi\u00e9rcoles a las 14h.<\/p>\n<p>La ceremonia se celebrar\u00e1 el jueves 16 de noviembre las 12h.<\/p>\n<p style=\"text-align: right\">R.I.P<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os informamos del fallecimiento de la estimada Sra Leonor Garuz Blanco, fundadora de Colegio Molina. El velatorio tendr\u00e1 lugar en&#8230;<\/p>\n","protected":false},"author":3,"featured_media":5957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-5960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sra. Leonor Garuz Blanco - Centros de ense\u00f1anza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sra. Leonor Garuz Blanco - Centros de ense\u00f1anza\" \/>\n<meta property=\"og:description\" content=\"Os informamos del fallecimiento de la estimada Sra Leonor Garuz Blanco, fundadora de Colegio Molina. El velatorio tendr\u00e1 lugar en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/\" \/>\n<meta property=\"og:site_name\" content=\"Centros de ense\u00f1anza\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-14T19:46:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-14T19:52:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centresmolina.com\/centreensenyament\/files\/2017\/11\/In-memoriam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"260\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmolina\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmolina\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/\"},\"author\":{\"name\":\"webmolina\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#\\\/schema\\\/person\\\/308d85d274adff04b5c51d47e8aff6cc\"},\"headline\":\"Sra. Leonor Garuz Blanco\",\"datePublished\":\"2017-11-14T19:46:11+00:00\",\"dateModified\":\"2017-11-14T19:52:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/\"},\"wordCount\":54,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2017\\\/11\\\/In-memoriam.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/\",\"url\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/\",\"name\":\"Sra. Leonor Garuz Blanco - Centros de ense\u00f1anza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2017\\\/11\\\/In-memoriam.jpg\",\"datePublished\":\"2017-11-14T19:46:11+00:00\",\"dateModified\":\"2017-11-14T19:52:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#\\\/schema\\\/person\\\/308d85d274adff04b5c51d47e8aff6cc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2017\\\/11\\\/In-memoriam.jpg\",\"contentUrl\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2017\\\/11\\\/In-memoriam.jpg\",\"width\":260,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/2017\\\/11\\\/14\\\/sra-leonor-garuz-blanco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sra. Leonor Garuz Blanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#website\",\"url\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/\",\"name\":\"Centros de ense\u00f1anza\",\"description\":\"Centres Molina - Centros de ense\u00f1anza\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#\\\/schema\\\/person\\\/308d85d274adff04b5c51d47e8aff6cc\",\"name\":\"webmolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38db407e1ab9b284bf45e3bff4ec5cf1e034e364f09b2ee054619614662a717b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38db407e1ab9b284bf45e3bff4ec5cf1e034e364f09b2ee054619614662a717b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38db407e1ab9b284bf45e3bff4ec5cf1e034e364f09b2ee054619614662a717b?s=96&d=mm&r=g\",\"caption\":\"webmolina\"},\"url\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/es\\\/author\\\/webmolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sra. Leonor Garuz Blanco - Centros de ense\u00f1anza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/","og_locale":"es_ES","og_type":"article","og_title":"Sra. Leonor Garuz Blanco - Centros de ense\u00f1anza","og_description":"Os informamos del fallecimiento de la estimada Sra Leonor Garuz Blanco, fundadora de Colegio Molina. El velatorio tendr\u00e1 lugar en...","og_url":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/","og_site_name":"Centros de ense\u00f1anza","article_published_time":"2017-11-14T19:46:11+00:00","article_modified_time":"2017-11-14T19:52:25+00:00","og_image":[{"width":260,"height":194,"url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2017\/11\/In-memoriam.jpg","type":"image\/jpeg"}],"author":"webmolina","twitter_misc":{"Escrito por":"webmolina"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#article","isPartOf":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/"},"author":{"name":"webmolina","@id":"https:\/\/centresmolina.com\/centreensenyament\/#\/schema\/person\/308d85d274adff04b5c51d47e8aff6cc"},"headline":"Sra. Leonor Garuz Blanco","datePublished":"2017-11-14T19:46:11+00:00","dateModified":"2017-11-14T19:52:25+00:00","mainEntityOfPage":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/"},"wordCount":54,"commentCount":0,"image":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#primaryimage"},"thumbnailUrl":"https:\/\/centresmolina.com\/centreensenyament\/files\/2017\/11\/In-memoriam.jpg","articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/","url":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/","name":"Sra. Leonor Garuz Blanco - Centros de ense\u00f1anza","isPartOf":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/#website"},"primaryImageOfPage":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#primaryimage"},"image":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#primaryimage"},"thumbnailUrl":"https:\/\/centresmolina.com\/centreensenyament\/files\/2017\/11\/In-memoriam.jpg","datePublished":"2017-11-14T19:46:11+00:00","dateModified":"2017-11-14T19:52:25+00:00","author":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/#\/schema\/person\/308d85d274adff04b5c51d47e8aff6cc"},"breadcrumb":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#primaryimage","url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2017\/11\/In-memoriam.jpg","contentUrl":"https:\/\/centresmolina.com\/centreensenyament\/files\/2017\/11\/In-memoriam.jpg","width":260,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/centresmolina.com\/centreensenyament\/es\/2017\/11\/14\/sra-leonor-garuz-blanco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centresmolina.com\/centreensenyament\/es\/"},{"@type":"ListItem","position":2,"name":"Sra. Leonor Garuz Blanco"}]},{"@type":"WebSite","@id":"https:\/\/centresmolina.com\/centreensenyament\/#website","url":"https:\/\/centresmolina.com\/centreensenyament\/","name":"Centros de ense\u00f1anza","description":"Centres Molina - Centros de ense\u00f1anza","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centresmolina.com\/centreensenyament\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/centresmolina.com\/centreensenyament\/#\/schema\/person\/308d85d274adff04b5c51d47e8aff6cc","name":"webmolina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/38db407e1ab9b284bf45e3bff4ec5cf1e034e364f09b2ee054619614662a717b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38db407e1ab9b284bf45e3bff4ec5cf1e034e364f09b2ee054619614662a717b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38db407e1ab9b284bf45e3bff4ec5cf1e034e364f09b2ee054619614662a717b?s=96&d=mm&r=g","caption":"webmolina"},"url":"https:\/\/centresmolina.com\/centreensenyament\/es\/author\/webmolina\/"}]}},"_links":{"self":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/posts\/5960\/"}],"collection":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/posts\/"}],"about":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/types\/post\/"}],"author":[{"embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/users\/3\/"}],"replies":[{"embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/comments\/?post=5960"}],"version-history":[{"count":2,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/posts\/5960\/revisions\/"}],"predecessor-version":[{"id":5963,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/posts\/5960\/revisions\/5963\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/media\/5957\/"}],"wp:attachment":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/media\/?parent=5960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/categories\/?post=5960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/es\/wp-json\/wp\/v2\/tags\/?post=5960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}