{"id":2521,"date":"2016-05-30T20:23:14","date_gmt":"2016-05-30T20:23:14","guid":{"rendered":"http:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg"},"modified":"2016-05-30T20:23:14","modified_gmt":"2016-05-30T20:23:14","slug":"taller-rcp-1r-i-2n-eso-10","status":"inherit","type":"attachment","link":"https:\/\/centresmolina.com\/centreensenyament\/taller-rcp-1r-i-2n-eso-10\/","title":{"rendered":"Taller RCP 1r i 2n ESO (10)"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-2521","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taller RCP 1r i 2n ESO (10) - Centros de ense\u00f1anza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taller RCP 1r i 2n ESO (10) - Centros de ense\u00f1anza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Centros de ense\u00f1anza\" \/>\n<meta property=\"og:image\" content=\"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2016\\\/05\\\/Taller-RCP-1r-i-2n-ESO-10.jpg\",\"url\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2016\\\/05\\\/Taller-RCP-1r-i-2n-ESO-10.jpg\",\"name\":\"Taller RCP 1r i 2n ESO (10) - Centros de ense\u00f1anza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#website\"},\"datePublished\":\"2016-05-30T20:23:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2016\\\/05\\\/Taller-RCP-1r-i-2n-ESO-10.jpg#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2016\\\/05\\\/Taller-RCP-1r-i-2n-ESO-10.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/files\\\/2016\\\/05\\\/Taller-RCP-1r-i-2n-ESO-10.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taller RCP 1r i 2n ESO (10)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/#website\",\"url\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/\",\"name\":\"Centros de ense\u00f1anza\",\"description\":\"Centres Molina - Centros de ense\u00f1anza\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/centresmolina.com\\\/centreensenyament\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taller RCP 1r i 2n ESO (10) - Centros de ense\u00f1anza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","og_locale":"ca_ES","og_type":"article","og_title":"Taller RCP 1r i 2n ESO (10) - Centros de ense\u00f1anza","og_url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","og_site_name":"Centros de ense\u00f1anza","og_image":[{"width":1280,"height":960,"url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","name":"Taller RCP 1r i 2n ESO (10) - Centros de ense\u00f1anza","isPartOf":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/#website"},"datePublished":"2016-05-30T20:23:14+00:00","breadcrumb":{"@id":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/centresmolina.com\/centreensenyament\/"},{"@type":"ListItem","position":2,"name":"Taller RCP 1r i 2n ESO (10)"}]},{"@type":"WebSite","@id":"https:\/\/centresmolina.com\/centreensenyament\/#website","url":"https:\/\/centresmolina.com\/centreensenyament\/","name":"Centros de ense\u00f1anza","description":"Centres Molina - Centros de ense\u00f1anza","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/centresmolina.com\/centreensenyament\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10-300x225.jpg 300w, https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10-1024x768.jpg 1024w, https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":960,"file":"2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","sizes":{"thumbnail":{"file":"Taller-RCP-1r-i-2n-ESO-10-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10-150x150.jpg"},"medium":{"file":"Taller-RCP-1r-i-2n-ESO-10-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10-300x225.jpg"},"large":{"file":"Taller-RCP-1r-i-2n-ESO-10-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10-1024x768.jpg"},"full":{"file":"Taller-RCP-1r-i-2n-ESO-10.jpg","width":1280,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg"}},"image_meta":{"aperture":2.20000000000000017763568394002504646778106689453125,"credit":"","camera":"Aquaris E4","caption":"","created_timestamp":1464262201,"copyright":"","focal_length":"3.5","iso":"320","shutter_speed":"0.029986","title":"","orientation":1}},"post":null,"source_url":"https:\/\/centresmolina.com\/centreensenyament\/files\/2016\/05\/Taller-RCP-1r-i-2n-ESO-10.jpg","filename":"Taller-RCP-1r-i-2n-ESO-10.jpg","filesize":224820,"_links":{"self":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/wp-json\/wp\/v2\/media\/2521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/centresmolina.com\/centreensenyament\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/centresmolina.com\/centreensenyament\/wp-json\/wp\/v2\/comments?post=2521"}]}}